{"id":100552,"date":"2022-08-30T16:25:10","date_gmt":"2022-08-30T16:25:10","guid":{"rendered":"https:\/\/interac1.wpengine.com\/?post_type=content&#038;p=100552"},"modified":"2024-02-09T15:06:11","modified_gmt":"2024-02-09T20:06:11","slug":"ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes","status":"publish","type":"content","link":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/","title":{"rendered":"Ce que signifie un milliard de transactions par Virement <i>Interac<\/i> pour les entreprises canadiennes"},"content":{"rendered":"\n<p>En avril 2022, Interac a franchi une \u00e9tape importante dans le d\u00e9placement de fonds, l&rsquo;utilisation du service Virement <em>Interac<\/em> ayant d\u00e9pass\u00e9 <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/nouvelles\/virements-interac-plus-de-1-milliard-de-transactions-dans-les-12-derniers-mois\/\">le milliard de transactions<\/a> sur une p\u00e9riode de 12 mois. De toutes ces transactions par Virement <em>Interac<\/em>, <strong>19 % concernaient une entreprise<\/strong>. En fait, <strong>pr\u00e8s de la moiti\u00e9 (47 %) des utilisateurs du service Virement<em> Interac<\/em><\/strong> ont utilis\u00e9 ce service pour payer une petite entreprise, pratique qui <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/nouvelles\/un-sondage-interac-revele-que-pres-des-trois-quarts-des-entreprises-canadiennes-prevoient-delaisser-les-cheques-au-cours-des-cinq-prochaines-annees\/\" target=\"_blank\" rel=\"noreferrer noopener\">devient plus courante<\/a>.<\/p>\n\n\n\n<p>Au-del\u00e0 des chiffres, ces statistiques symbolisent des <em>millions <\/em>d&rsquo;entreprises au Canada qui ont fait preuve de r\u00e9silience, d&rsquo;agilit\u00e9 et de cr\u00e9ativit\u00e9 en passant aux paiements num\u00e9riques depuis la pand\u00e9mie de la Covid-19. Aujourd&rsquo;hui, alors que les entreprises de toutes tailles dans tous les secteurs d&rsquo;activit\u00e9 s&rsquo;adaptent et se d\u00e9veloppent en fonction de l&rsquo;\u00e9volution des besoins de leurs clients, le milliard de transactions avec le service Virement <em>Interac<\/em> t\u00e9moigne de la pertinence croissante des paiements en ligne directs et en temps r\u00e9el (y compris les paiements commerciaux) pour tous les Canadiens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-facons-dont-le-traitement-des-paiements-numeriques-a-aide-les-entreprises\">Fa\u00e7ons dont le traitement des paiements num\u00e9riques a aid\u00e9 les entreprises<\/h2>\n\n\n\n<p>Depuis 20 ans, les Canadiens utilisent le <a href=\"https:\/\/www.interac.ca\/fr\/consommateur\/produits\/virement-interac\/\">service Virement <em>Interac<\/em><\/a> dans leur vie personnelle pour envoyer et recevoir de l&rsquo;argent rapidement et en toute s\u00e9curit\u00e9. Cependant, <a href=\"https:\/\/www.interac.ca\/content\/ideas\/covid-19-accelerating-digital-trends-in-canada\/\">la pand\u00e9mie a acc\u00e9l\u00e9r\u00e9 le passage aux paiements num\u00e9riques sans contact<\/a>, et cette confiance et cette familiarit\u00e9 se sont naturellement traduites par l&rsquo;utilisation du service pour payer des produits et des services. Beaucoup d&rsquo;entreprises et d&rsquo;entrepreneurs se sont tourn\u00e9s vers le service Virement <em>Interac <\/em>pour accepter les paiements num\u00e9riques des clients, ce qui a constitu\u00e9 un \u00e9l\u00e9ment essentiel de ce virage.<\/p>\n\n\n\n<p>Anurag Kar, notre vice-pr\u00e9sident adjoint, Produits de virement de fonds, d\u00e9crit l&rsquo;impact de la pand\u00e9mie sur la num\u00e9risation des paiements dans <a href=\"https:\/\/www.pymnts.com\/news\/faster-payments\/2022\/canadas-real-time-rollout-offers-glimpse-of-payments-possibilities\/\">une interview r\u00e9cente avec PYMNTS.com<\/a> :<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Interview-Clip-1.mp3\"><\/audio><\/figure>\n\n\n\n<section id=\"accordion-block_fdfac449a81228ae531c5db244c6d7d7\" class=\"accordion-content-block\" style=\"margin-top: 0px; margin-bottom: 0px;\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x align-center\">\n            <div class=\"cell small-12\">\n                            <ul class=\"accordion\" data-accordion data-deep-link=\"false\" data-update-history=\"false\" data-deep-link-smudge=\"false\" data-deep-link-smudge-delay=\"500\" id=\"deeplinked-accordion\" data-allow-all-closed=\"true\">\n                                <li class=\"accordion-item\" data-accordion-item><a href=\"#\" class=\"accordion-title\"><h6>Anurag Kar explique l&rsquo;impact de la pand\u00e9mie sur la num\u00e9risation des paiements. \u00ab En savoir plus \u00bb<\/h6><\/a> <div id=\"\" class=\"accordion-content\" data-tab-content><p>Au d\u00e9but de la pand\u00e9mie, pratiquement toutes les entreprises ont d\u00fb num\u00e9riser leur exp\u00e9rience de paiement. Si vous n&rsquo;aviez pas la capacit\u00e9 de collecter les paiements ou d&rsquo;interagir avec vos clients de fa\u00e7on num\u00e9rique, vous auriez du mal \u00e0 leur offrir des services et \u00e0 r\u00e9aliser des ventes. Ce que les entreprises attendent vraiment du virement \u00e9lectronique, c&rsquo;est une solution rapide, simple et en temps r\u00e9el pour recevoir des fonds. C&rsquo;est pourquoi beaucoup d&rsquo;entreprises ont commenc\u00e9 \u00e0 l&rsquo;adopter comme service de paiement num\u00e9rique.<\/p>\n<p>Du point de vue des consommateurs, nous constatons qu&rsquo;ils continuent \u00e0 relever les d\u00e9fis li\u00e9s \u00e0 la pand\u00e9mie et d\u00e9pensent peut-\u00eatre plus d&rsquo;argent pour g\u00e9rer leur cycle de vie financier.<\/p>\n<p>Qu&rsquo;est-ce que le service m&rsquo;offre en tant que consommateur ? Je peux sortir avec mes amis et vivre \u00e0 nouveau ce genre d&rsquo;exp\u00e9riences alors que la vie reprend son cours, et je peux ensuite les rembourser ou partager la facture imm\u00e9diatement. C&rsquo;est pourquoi nous avons assist\u00e9 \u00e0 une adoption massive et \u00e0 une utilisation haut de gamme au cours de la pand\u00e9mie. Tout le monde voulait essentiellement avoir acc\u00e8s au paiement num\u00e9rique pour rembourser ou \u00eatre rembours\u00e9.<\/p>\n<\/div><\/li>                <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<p>Pour le traitement quotidien des paiements, Virement <em>Interac<\/em> aide les entreprises \u00e0 renforcer leurs relations avec leurs clients, leurs fournisseurs et leurs employ\u00e9s. <a href=\"https:\/\/www.interac.ca\/fr\/comment-utiliser\/virement-interac\/comment-demarrer-avec-virement-interac-pour-les-entreprises\/\">Gr\u00e2ce \u00e0 la simplicit\u00e9 de l&rsquo;exp\u00e9rience utilisateur<\/a> (il suffit d&rsquo;un compte courriel ou d&rsquo;un num\u00e9ro de t\u00e9l\u00e9phone et d&rsquo;un compte bancaire canadien), les entreprises peuvent instantan\u00e9ment accepter de l&rsquo;argent pour de nouveaux produits et services, mettre \u00e0 l\u2019essai divers mod\u00e8les d&rsquo;affaires et payer leurs fournisseurs et leurs employ\u00e9s avec une \u00ab&nbsp;trace documentaire&nbsp;\u00bb num\u00e9rique.<\/p>\n\n\n\n<p>C&rsquo;\u00e9tait particuli\u00e8rement important \u00e0 un moment o\u00f9 les entreprises devaient trouver de nouveaux moyens d&rsquo;atteindre leurs clients et o\u00f9 les flux de liquidit\u00e9 \u00e9taient impr\u00e9visibles. Lorsque la pand\u00e9mie a frapp\u00e9, de petites entreprises comme <a href=\"https:\/\/www.interac.ca\/content\/business\/video-the-value-of-contactless-and-secure-payments-in-a-pandemic\/\">Simone&rsquo;s Caribbean on the Danforth<\/a>, ont d\u00fb passer de la vente en salle \u00e0 manger \u00e0 la vente \u00e0 emporter et de traiteur. Le Virement <em>Interac<\/em> a jou\u00e9 un r\u00f4le crucial dans la survie de l&rsquo;entreprise. Il permettait de se faire payer directement et instantan\u00e9ment, sans probl\u00e8me, pour les nouveaux services de traiteur.&nbsp;<\/p>\n\n\n\n<p>Simultan\u00e9ment, des entrepreneurs comme <a href=\"https:\/\/www.interac.ca\/content\/business\/interac-helps-a-toronto-brand-pivot-during-the-pandemic\/\">Outclass, cr\u00e9ateur de v\u00eatements pour hommes fabriqu\u00e9s \u00e0 Toronto<\/a>, a utilis\u00e9 le Virement <em>Interac<\/em> pour entretenir et d\u00e9velopper des relations solides avec des fournisseurs et des fabricants locaux. Pour <a href=\"https:\/\/www.interac.ca\/content\/business\/power-of-community-how-this-2slgbtq-vegan-pasta-company-thrived-during-the-pandemic\/\">NONA Vegan, entreprise de sauce pour p\u00e2tes \u00e0 base de plantes<\/a>, la plateforme est devenue un outil de paiement incontournable pour g\u00e9rer les flux de tr\u00e9sorerie en temps r\u00e9el et survivre aux fluctuations constantes de la pand\u00e9mie. \u00ab&nbsp;Tout \u00e9tait tellement impr\u00e9visible. Donc, notre flux de tr\u00e9sorerie \u00e9tait hyper serr\u00e9.&nbsp;\u00bb<\/p>\n\n\n\n<p>M\u00eame si la pand\u00e9mie a boulevers\u00e9 le monde des affaires, elle a \u00e9galement acc\u00e9l\u00e9r\u00e9 la tendance \u00e0 la \u00ab&nbsp;grande d\u00e9mission&nbsp;\u00bb et les occasions de profiter de la vie au maximum. <a href=\"https:\/\/www.interac.ca\/content\/business\/video-kira-noel-shares-fast-and-easy-solutions-for-running-your-own-business\/\">Kira Noel Photography<\/a> est n\u00e9e d&rsquo;un projet passionnel qui s&rsquo;est rapidement transform\u00e9 en une entreprise viable. Ce sont les enfants de Kira qui l&rsquo;ont incit\u00e9e \u00e0 lancer sa propre entreprise de photographie, mais tr\u00e8s vite, les amis et la famille ont commenc\u00e9 \u00e0 lui demander de prendre leurs photos. Les Virement <em>Interac<\/em> est devenu une solution rapide et facile pour l&rsquo;aider \u00e0 lancer son entreprise, sans avoir \u00e0 courir apr\u00e8s les paiements ou \u00e0 attendre que les ch\u00e8ques soient compens\u00e9s.<\/p>\n\n\n\n<p>Faites d\u00e9filer les images pour voir comment les petites entreprises ont utilis\u00e9 le service de Virement <em>Interac<\/em> pour s&rsquo;adapter et passer aux paiements num\u00e9riques :&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-virage-aux-virements-electroniques-d-argent\">Virage aux virements \u00e9lectroniques d\u2019argent<\/h3>\n\n\n\n\n\n    <section id=\"carousel-block_32278c6795c8c1db2ff221bc96ca3c51\" class=\"split-carousel grid-container full\" style=\"margin-top: px; margin-bottom: px;\">\n        \n                            <div class=\"slickSlider\">\n                                        <div class=\"slide\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x grid-padding-x\">\n                                                                <div class=\"cell slide-content small-12 medium-5 small-order-2 medium-order-1\">\n                                                                                                        <h1 class=\"slide-title\">Le restaurant jama\u00efcain et carib\u00e9en Simone&rsquo;s<\/h1>\n                                    <p>\u00ab Le service Virement <i>Interac<\/i> m&rsquo;offre un moyen rapide d&rsquo;\u00eatre pay\u00e9e en tant qu&rsquo;entrepreneure dirigeant une petite entreprise. Je suis r\u00e9mun\u00e9r\u00e9e tout de suite, c&rsquo;est g\u00e9nial. \u00bb<\/p>\n                                                                            <a href=\"https:\/\/www.interac.ca\/content\/business\/video-the-value-of-contactless-and-secure-payments-in-a-pandemic\/\" class=\"inline-link\"><span>En savoir plus<\/span><\/a>\n                                                                    <\/div>\n                                                                    <div class=\"cell small-12 medium-7 slide-image small-order-1 medium-order-2\">\n                                                                    <figure class=\"figure\">\n                                        <img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5.jpg.webp\" class=\"attachment-fdivl size-fdivl lazyload\" alt=\"Simone Lawrence Ogilvie, propri\u00e9taire du restaurant Simone\u2019s Caribbean \u00e0 Toronto.\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5.jpg.webp 2048w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5-300x200.jpg.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5-1024x683.jpg.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5-768x512.jpg.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-5-1536x1025.jpg.webp 1536w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                    <\/figure>\n                                <\/div>\n                                                                <\/div>\n                                                        <\/div>\n                    <\/div>\n                                        <div class=\"slide\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x grid-padding-x\">\n                                                                <div class=\"cell slide-content small-12 medium-5 small-order-2 medium-order-1\">\n                                                                                                        <h1 class=\"slide-title\">Outclass : Vente au d\u00e9tail de mode pour hommes<\/h1>\n                                    <p>\u00ab Nous avons des liens tr\u00e8s personnels avec nos fournisseurs. Nous envoyons de l&rsquo;argent \u00e0 nos fournisseurs par Virement <i>Interac<\/i>, car nous savons qu&rsquo;ils re\u00e7oivent l&rsquo;argent plus rapidement, et c&rsquo;est important pour nous. \u00bb<\/p>\n                                                                            <a href=\"https:\/\/www.interac.ca\/content\/business\/interac-helps-a-toronto-brand-pivot-during-the-pandemic\/\" class=\"inline-link\"><span>En savoir plus<\/span><\/a>\n                                                                    <\/div>\n                                                                    <div class=\"cell small-12 medium-7 slide-image small-order-1 medium-order-2\">\n                                                                    <figure class=\"figure\">\n                                        <img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3.jpg.webp\" class=\"attachment-fdivl size-fdivl lazyload\" alt=\"Matteo Sgaramella, fondateur de OUTCLASS, pose avec des v\u00eatements de sa collection.\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3.jpg.webp 2048w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3-300x200.jpg.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3-1024x683.jpg.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3-768x512.jpg.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-3-1536x1025.jpg.webp 1536w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                    <\/figure>\n                                <\/div>\n                                                                <\/div>\n                                                        <\/div>\n                    <\/div>\n                                        <div class=\"slide\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x grid-padding-x\">\n                                                                <div class=\"cell slide-content small-12 medium-5 small-order-2 medium-order-1\">\n                                                                                                        <h1 class=\"slide-title\">NONA Vegan : Sauces italiennes \u00e0 base de plantes<\/h1>\n                                    <p>\u00ab Je peux envoyer de l&rsquo;argent et savoir qu&rsquo;il sort de mon compte \u00e0 ce moment-l\u00e0, plut\u00f4t que d&rsquo;envoyer un ch\u00e8que et ne pas savoir quand celui-ci va affecter le solde de ma tr\u00e9sorerie. \u00bb<\/p>\n                                                                            <a href=\"https:\/\/www.interac.ca\/content\/business\/power-of-community-how-this-2slgbtq-vegan-pasta-company-thrived-during-the-pandemic\/\" class=\"inline-link\"><span>En savoir plus<\/span><\/a>\n                                                                    <\/div>\n                                                                    <div class=\"cell small-12 medium-7 slide-image small-order-1 medium-order-2\">\n                                                                    <figure class=\"figure\">\n                                        <img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1.jpg.webp\" class=\"attachment-fdivl size-fdivl lazyload\" alt=\"Kailey Gilchrist chef de la direction de NONA Vegan, tient un des produits de son entreprise.\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1.jpg.webp 2048w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1-300x200.jpg.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1-1024x683.jpg.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1-768x512.jpg.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-1-1536x1025.jpg.webp 1536w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                    <\/figure>\n                                <\/div>\n                                                                <\/div>\n                                                        <\/div>\n                    <\/div>\n                                        <div class=\"slide\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x grid-padding-x\">\n                                                                <div class=\"cell slide-content small-12 medium-5 small-order-2 medium-order-1\">\n                                                                                                        <h1 class=\"slide-title\">Kira Noel Photography: Photographie familiale<\/h1>\n                                    <p>\u00ab Je ne peux pas me permettre d&rsquo;attendre que les ch\u00e8ques soient compens\u00e9s ou de poursuivre les gens si un ch\u00e8que est sans provision. Le service de Virement <i>Interac<\/i> est une solution rapide et facile pour mes clients et mon entreprise. \u00bb<\/p>\n                                                                            <a href=\"https:\/\/www.interac.ca\/content\/business\/video-kira-noel-shares-fast-and-easy-solutions-for-running-your-own-business\/\" class=\"inline-link\"><span>En savoir plus<\/span><\/a>\n                                                                    <\/div>\n                                                                    <div class=\"cell small-12 medium-7 slide-image small-order-1 medium-order-2\">\n                                                                    <figure class=\"figure\">\n                                        <img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4.jpg.webp\" class=\"attachment-fdivl size-fdivl lazyload\" alt=\"La photographe Kira Noel prend une photo de deux enfants dans une chambre \u00e0 coucher.\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4.jpg.webp 2048w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4-300x200.jpg.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4-1024x683.jpg.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4-768x512.jpg.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-4-1536x1025.jpg.webp 1536w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                    <\/figure>\n                                <\/div>\n                                                                <\/div>\n                                                        <\/div>\n                    <\/div>\n                                        <div class=\"slide\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x grid-padding-x\">\n                                                                <div class=\"cell slide-content small-12 medium-5 small-order-2 medium-order-1\">\n                                                                                                        <h1 class=\"slide-title\">Lignum Honey: du miel 100 % naturel<\/h1>\n                                    <p>\u00ab Depuis le d\u00e9but, Interac a \u00e9t\u00e9 un pilier essentiel pour mon entreprise. Plus il est facile pour mes clients de transf\u00e9rer des paiements, plus l&rsquo;exp\u00e9rience que nous pouvons leur offrir est transparente. \u00bb<\/p>\n                                                                            <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/comment-lentreprise-lignum-honey-fleurit-grace-a-la-plateforme-de-virement-interac\/\" class=\"inline-link\"><span>En savoir plus<\/span><\/a>\n                                                                    <\/div>\n                                                                    <div class=\"cell small-12 medium-7 slide-image small-order-1 medium-order-2\">\n                                                                    <figure class=\"figure\">\n                                        <img decoding=\"async\" width=\"2048\" height=\"1366\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2.jpg.webp\" class=\"attachment-fdivl size-fdivl lazyload\" alt=\"Une main tient un pot de miel Lignum.\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2.jpg.webp 2048w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2-300x200.jpg.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2-1024x683.jpg.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2-768x512.jpg.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_Carousel-2-1536x1025.jpg.webp 1536w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1366;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                    <\/figure>\n                                <\/div>\n                                                                <\/div>\n                                                        <\/div>\n                    <\/div>\n                                    <\/div>\n                <\/section>\n    \n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-des-paiements-acceleres-avec-virement-interac-pour-les-entreprises\">Des paiements acc\u00e9l\u00e9r\u00e9s avec Virement <em>Interac <\/em>pour les entreprises<\/h2>\n\n\n\n<p>Le milliard de transactions par Virement <em>Interac<\/em> t\u00e9moigne \u00e9galement de la demande croissante pour les paiements commerciaux en temps r\u00e9el. Qu&rsquo;il s&rsquo;agisse de recevoir les paiements de clients ou de payer les vendeurs, les fournisseurs, les entrepreneurs et les employ\u00e9s, le Virement <em>Interac<\/em> devient rapidement une pratique commerciale courante qui permet d&rsquo;am\u00e9liorer la rapidit\u00e9, l&rsquo;efficacit\u00e9 et la tr\u00e9sorerie des op\u00e9rations, et d&rsquo;instaurer la confiance.<\/p>\n\n\n\n<p>Apr\u00e8s l&rsquo;intensit\u00e9 et l&rsquo;isolement de la pand\u00e9mie, les Canadiens veulent <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/nouvelles\/comment-des-millions-de-moments-partages-ont-mene-a-un-milliard-de-paiements-avec-le-service-virement-interac\/\">rattraper le temps perdu avec les joies simples des exp\u00e9riences partag\u00e9es<\/a>, tout en faisant face \u00e0 la r\u00e9alit\u00e9 difficile de l&rsquo;augmentation du co\u00fbt de la vie. En tant que paiement num\u00e9rique bas\u00e9 sur des fonds disponibles en temps r\u00e9el, le service de Virement <em>Interac<\/em> permet aux consommateurs canadiens de partager les co\u00fbts avec leurs amis et leur famille tout en utilisant leur propre argent par l&rsquo;interm\u00e9diaire d&rsquo;un service qu&rsquo;ils connaissent et auquel ils font confiance.<\/p>\n\n\n\n<p>Selon M. Kar, <a href=\"https:\/\/www.pymnts.com\/opinion\/2022\/digital-real-time-payments-will-unlock-efficiencies-for-canadians\/\">les paiements num\u00e9riques en temps r\u00e9el r\u00e9v\u00e8leront l&rsquo;efficacit\u00e9 et la commodit\u00e9 pour les Canadiens<\/a> : \u00ab&nbsp;Ces types de transactions continueront de prendre de l&rsquo;importance \u00e0 travers les segments des consommateurs et des entreprises.&nbsp;\u00bb<\/p>\n\n\n\n<p>Bien que le service Virement <em>Interac <\/em>ait \u00e9t\u00e9 cr\u00e9\u00e9 en tant que service pair-\u00e0-pair, M. Kar explique que \u00ab&nbsp;ce que les entreprises voient vraiment dans le service Virement <em>Interac<\/em>, c&rsquo;est une capacit\u00e9 rapide, simple et en temps r\u00e9el de recevoir des fonds. C&rsquo;est pourquoi nous avons commenc\u00e9 \u00e0 voir beaucoup d&rsquo;entreprises l&rsquo;adopter.&nbsp;\u00bb<\/p>\n\n\n\n<p>Si la pand\u00e9mie a incit\u00e9 les entreprises \u00e0 commencer \u00e0 utiliser le service de Virement<em> Interac<\/em>, beaucoup ont rapidement compris la puissance des paiements en temps r\u00e9el <a href=\"https:\/\/www.theglobeandmail.com\/business\/adv\/article-cheques-are-out-digital-payments-are-in-how-interac-e-transfer-for\/\">pour \u00e9liminer les ch\u00e8ques et les factures papier,<\/a> avec pour r\u00e9sultat des flux de tr\u00e9sorerie et des rapprochements plus rapides, <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/nouvelles\/un-sondage-interac-revele-que-pres-des-trois-quarts-des-entreprises-canadiennes-prevoient-delaisser-les-cheques-au-cours-des-cinq-prochaines-annees\/\" target=\"_blank\" rel=\"noreferrer noopener\">tendance qui est appel\u00e9e \u00e0 se maintenir<\/a>. De mars 2020 \u00e0 avril 2021, les utilisateurs commerciaux actifs ont augment\u00e9 de 26,7 %, comparativement au taux de croissance global des utilisateurs actifs de la plateforme, qui est d&rsquo;un peu plus de 10 %.<\/p>\n\n\n\n<p>En r\u00e9ponse \u00e0 l&rsquo;utilisation croissante de la plateforme de paiement par les entreprises, l&rsquo;\u00e9quipe d&rsquo;Interac a cr\u00e9\u00e9 le <a href=\"https:\/\/www.interac.ca\/fr\/entreprise\/nos-solutions\/virement-interac\/\">service Virement <em>Interac<\/em> pour les entreprises<\/a>. La version commerciale am\u00e9lior\u00e9e a \u00e9t\u00e9 <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/les-entreprises-canadiennes-simplifient-leurs-paiements-avec-virement-interac-pour-les-entreprises-voici-comment\/\">con\u00e7ue pour r\u00e9pondre aux besoins d\u2019entreprises<\/a> de toutes tailles, avec des confirmations en temps r\u00e9el, des limites de transaction plus \u00e9lev\u00e9es (jusqu&rsquo;\u00e0 25 000 $), des options d&rsquo;acheminement souples, des donn\u00e9es de versement riches et la possibilit\u00e9 de traiter des transactions en lot et de rapprocher les factures automatiquement. <\/p>\n\n\n\n<p>M. Kar explique le raisonnement qui sous-tend le lancement de Virement <em>Interac<\/em> pour les entreprises et les possibilit\u00e9s de transferts d&rsquo;argent num\u00e9riques au Canada :<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Interview-Clip-2.mp3\"><\/audio><\/figure>\n\n\n\n<section id=\"accordion-block_31368db73b4b1b8c5112b31e113851a3\" class=\"accordion-content-block\" style=\"margin-top: 0px; margin-bottom: 0px;\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x align-center\">\n            <div class=\"cell small-12\">\n                            <ul class=\"accordion\" data-accordion data-deep-link=\"false\" data-update-history=\"false\" data-deep-link-smudge=\"false\" data-deep-link-smudge-delay=\"500\" id=\"deeplinked-accordion\" data-allow-all-closed=\"true\">\n                                <li class=\"accordion-item\" data-accordion-item><a href=\"#\" class=\"accordion-title\"><h6>Anurag Kar parle du lancement du service Virement <i>Interac<\/i> pour les entreprises et des possibilit\u00e9s de transfert d&rsquo;argent au Canada. \u00ab En savoir plus \u00bb<\/h6><\/a> <div id=\"\" class=\"accordion-content\" data-tab-content><p>Nous venons de d\u00e9passer le milliard de transactions, ce qui repr\u00e9sente environ 338 milliards de dollars. En ce qui concerne <em>Interac<\/em> B2B, nous avons lanc\u00e9 sur le march\u00e9 un nouveau produit appel\u00e9 Virement <em>Interac<\/em> pour les entreprises. Il s&rsquo;agit essentiellement d&rsquo;un produit plus adapt\u00e9 aux besoin des entreprises. Notre produit initial \u00e9tait destin\u00e9 aux particuliers et permettait d&rsquo;envoyer de l&rsquo;argent \u00e0 une adresse \u00e9lectronique ou \u00e0 un num\u00e9ro de t\u00e9l\u00e9phone. Pour les entreprises, nous avons ajout\u00e9 la possibilit\u00e9 d&rsquo;envoyer de l&rsquo;argent \u00e0 des num\u00e9ros de compte et de joindre tout type de donn\u00e9es transactionnelles que quelqu&rsquo;un doit fournir au destinataire \u00e0 des fins de r\u00e9conciliation. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 lanc\u00e9e en ao\u00fbt 2021.<\/p>\n<p>Au cours des 18 prochains mois, nous allons d\u00e9velopper nos capacit\u00e9s de paiement en temps r\u00e9el. Nous envisageons deux voies de croissance. La premi\u00e8re concerne les entreprises. Nous voyons de plus en plus d&rsquo;utilisation du transfert \u00e9lectronique pour remplacer les instruments papier. Des choses comme les ch\u00e8ques peuvent \u00eatre prises en compte dans le transfert d&rsquo;argent, en fournissant les m\u00eames donn\u00e9es qu&rsquo;un ch\u00e8que dans un paiement num\u00e9rique &#8211; de sorte que quelqu&rsquo;un puisse instantan\u00e9ment r\u00e9concilier le paiement.<\/p>\n<\/div><\/li>                <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<p>Aujourd&rsquo;hui, ces paiements en temps r\u00e9el, riches en donn\u00e9es, aident les entreprises canadiennes \u00e0 <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/un-autre-outil-de-paiement-dans-votre-arsenal-avec-virement-interac-pour-les-entreprises\/\">simplifier leurs processus de comptabilit\u00e9 et \u00e0 acc\u00e9l\u00e9rer les strat\u00e9gies d\u2019\u00e9limination du papier<\/a> tout en facilitant plusieurs paiements \u00e0 la fois. En fait, chez Interac m\u00eame, <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/paiements-commerciaux-pourquoi-interac-investit-dans-sa-propre-transformation-financiere\/\">nous utilisons les paiements en lot par Virement <em>Interac<\/em><\/a> pour simplifier le processus de paie des travailleurs contractuels.<\/p>\n\n\n\n<p>Le service Virement <em>Interac<\/em> pour les entreprises <a href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/comment-mettre-a-profit-virement-interac-pour-les-entreprises\/\">s&rsquo;applique<\/a> \u00e0 tous les secteurs d&rsquo;activit\u00e9 et \u00e0 toutes les tailles d&rsquo;entreprise. Par exemple, <a href=\"https:\/\/www.interac.ca\/content\/business\/solutions-for-small-businesses-what-you-need-to-know-about-what-interac-e-transfer-can-do-for-your-business\/\">un propri\u00e9taire d\u2019une petite entreprise peut utiliser la solution<\/a> pour payer ses employ\u00e9s en toute s\u00e9curit\u00e9, tout en consacrant moins de temps \u00e0 l&rsquo;administration.&nbsp;<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, une franchise peut faciliter le paiement ponctuel des fournisseurs, et une compagnie d&rsquo;assurance peut l&rsquo;utiliser pour distribuer les demandes d&rsquo;indemnisation en temps r\u00e9el.<\/p>\n\n\n\n<p>M. Kar pense que l&rsquo;\u00e9conomie \u00e0 la demande sera l&rsquo;un des cas d&rsquo;utilisation les plus importants \u00e0 \u00e9merger par la suite. \u00ab&nbsp;Le paiement instantan\u00e9 des entrepreneurs est quelque chose qui est en train de se r\u00e9pandre aux \u00c9tats-Unis, et nous en avons maintenant la possibilit\u00e9 ici, gr\u00e2ce aux paiements en temps r\u00e9el.&nbsp;\u00bb <\/p>\n\n\n\n<p><a href=\"https:\/\/www.pymnts.com\/opinion\/2022\/digital-real-time-payments-will-unlock-efficiencies-for-canadians\/\">Pour ce qui est de l&rsquo;avenir<\/a>, il r\u00e9sume : \u00ab&nbsp;Nous pr\u00e9voyons que les paiements num\u00e9riques en temps r\u00e9el continueront d&rsquo;augmenter en termes d&rsquo;utilisation et d&rsquo;adoption, \u00e0 mesure que les organisations trouveront de nouveaux moyens de les int\u00e9grer dans les options de paiement.&nbsp;\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-favoriser-la-croissance-des-entreprises-canadiennes-et-de-l-economie-numerique\">Favoriser la croissance des entreprises canadiennes et de l&rsquo;\u00e9conomie num\u00e9rique<\/h2>\n\n\n\n<p>Interac est fier d&rsquo;aider les entreprises canadiennes \u00e0 adopter les paiements num\u00e9riques pour s&rsquo;adapter, cro\u00eetre et prosp\u00e9rer dans l&rsquo;\u00e9conomie num\u00e9rique d&rsquo;aujourd&rsquo;hui. Les entreprises doivent se questionner plus en plus pour adopter des solutions de paiement num\u00e9rique afin de maximiser les flux de tr\u00e9sorerie et les ressources internes, d&rsquo;autant plus que les Canadiens recherchent des exp\u00e9riences transparentes et en temps r\u00e9el tout en ayant le contr\u00f4le de leur propre argent. Derri\u00e8re le milliard de transactions Virement <em>Interac<\/em> se cache la v\u00e9ritable ing\u00e9niosit\u00e9 des entreprises canadiennes : am\u00e9liorer les moyens de connecter avec leurs clients.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.interac.ca\/fr\/entreprise\/nos-solutions\/virement-interac\/\"><img decoding=\"async\" width=\"1024\" height=\"286\" data-src=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_CTA-FR-1024x286.png.webp\" alt=\"\" class=\"wp-image-100353 lazyload\" data-srcset=\"https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_CTA-FR-1024x286.png.webp 1024w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_CTA-FR-300x84.png.webp 300w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_CTA-FR-768x215.png.webp 768w, https:\/\/www.interac.ca\/wp-content\/smush-webp\/2022\/08\/INT_IeTB-Growth_CTA-FR.png.webp 1166w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/286;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En avril 2022, Interac a franchi une \u00e9tape importante dans le d\u00e9placement de fonds, l&rsquo;utilisation du service Virement Interac ayant d\u00e9pass\u00e9 le milliard de transactions sur une p\u00e9riode de 12 mois. De toutes ces transactions par Virement Interac, 19 % concernaient une entreprise. En fait, pr\u00e8s de la moiti\u00e9 (47 %) des utilisateurs du service&hellip;<\/p>\n","protected":false},"author":28,"featured_media":100540,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"content-tags":[737,742,732],"content-category":[195],"spokespeople":[668],"in_the_know_post_format":[178],"class_list":["post-100552","content","type-content","status-publish","format-standard","has-post-thumbnail","hentry","content-tags-paiements","content-tags-petite-entreprise","content-tags-virement-interac","content-category-entreprises","spokespeople-anurag-kar-fr","in_the_know_post_format-article-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Virement INTERAC transforme les paiements d\u2019entreprises canadiennes<\/title>\n<meta name=\"description\" content=\"L\u2019utilisation de Virement INTERAC a surpass\u00e9 les 1 milliard de transactions. Autre jalon pour les entreprises canadiennes : Virement Interac pour les entreprises.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce que signifie un milliard de transactions par Virement Interac pour les entreprises canadiennes\" \/>\n<meta property=\"og:description\" content=\"En avril 2022, Interac a franchi une \u00e9tape importante dans le d\u00e9placement de fonds, l&#039;utilisation du service Virement Interac ayant d\u00e9pass\u00e9 le milliard de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/\" \/>\n<meta property=\"og:site_name\" content=\"Interac\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interac\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T20:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@interac\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/\",\"url\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/\",\"name\":\"Virement INTERAC transforme les paiements d\u2019entreprises canadiennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.interac.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/INT_IeTB-Growth_Header.jpg\",\"datePublished\":\"2022-08-30T16:25:10+00:00\",\"dateModified\":\"2024-02-09T20:06:11+00:00\",\"description\":\"L\u2019utilisation de Virement INTERAC a surpass\u00e9 les 1 milliard de transactions. Autre jalon pour les entreprises canadiennes : Virement Interac pour les entreprises.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.interac.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/INT_IeTB-Growth_Header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.interac.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/INT_IeTB-Growth_Header.jpg\",\"width\":2400,\"height\":1325,\"caption\":\"Femme portant un tablier dans un caf\u00e9 utilise une tablette\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/contenu\\\/entreprises\\\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ce que signifie un milliard de transactions par Virement Interac pour les entreprises canadiennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/\",\"name\":\"Interac\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#organization\",\"name\":\"Interac Corp.\",\"url\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.interac.ca\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Interac_Two-Colour_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.interac.ca\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Interac_Two-Colour_RGB.png\",\"width\":2210,\"height\":2210,\"caption\":\"Interac Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.interac.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interac\",\"https:\\\/\\\/x.com\\\/interac\",\"https:\\\/\\\/www.instagram.com\\\/interac\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interac-corp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/InteracBrand\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Virement INTERAC transforme les paiements d\u2019entreprises canadiennes","description":"L\u2019utilisation de Virement INTERAC a surpass\u00e9 les 1 milliard de transactions. Autre jalon pour les entreprises canadiennes : Virement Interac pour les entreprises.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/","og_locale":"fr_CA","og_type":"article","og_title":"Ce que signifie un milliard de transactions par Virement Interac pour les entreprises canadiennes","og_description":"En avril 2022, Interac a franchi une \u00e9tape importante dans le d\u00e9placement de fonds, l'utilisation du service Virement Interac ayant d\u00e9pass\u00e9 le milliard de","og_url":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/","og_site_name":"Interac","article_publisher":"https:\/\/www.facebook.com\/interac","article_modified_time":"2024-02-09T20:06:11+00:00","og_image":[{"width":2400,"height":1325,"url":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@interac","twitter_misc":{"Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/","url":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/","name":"Virement INTERAC transforme les paiements d\u2019entreprises canadiennes","isPartOf":{"@id":"https:\/\/www.interac.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/#primaryimage"},"image":{"@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Header.jpg","datePublished":"2022-08-30T16:25:10+00:00","dateModified":"2024-02-09T20:06:11+00:00","description":"L\u2019utilisation de Virement INTERAC a surpass\u00e9 les 1 milliard de transactions. Autre jalon pour les entreprises canadiennes : Virement Interac pour les entreprises.","breadcrumb":{"@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/#primaryimage","url":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Header.jpg","contentUrl":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/08\/INT_IeTB-Growth_Header.jpg","width":2400,"height":1325,"caption":"Femme portant un tablier dans un caf\u00e9 utilise une tablette"},{"@type":"BreadcrumbList","@id":"https:\/\/www.interac.ca\/fr\/contenu\/entreprises\/ce-que-signifie-un-milliard-de-transactions-par-virement-interac-pour-les-entreprises-canadiennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.interac.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ce que signifie un milliard de transactions par Virement Interac pour les entreprises canadiennes"}]},{"@type":"WebSite","@id":"https:\/\/www.interac.ca\/fr\/#website","url":"https:\/\/www.interac.ca\/fr\/","name":"Interac","description":"","publisher":{"@id":"https:\/\/www.interac.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.interac.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.interac.ca\/fr\/#organization","name":"Interac Corp.","url":"https:\/\/www.interac.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.interac.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/03\/Interac_Two-Colour_RGB.png","contentUrl":"https:\/\/www.interac.ca\/wp-content\/uploads\/2022\/03\/Interac_Two-Colour_RGB.png","width":2210,"height":2210,"caption":"Interac Corp."},"image":{"@id":"https:\/\/www.interac.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interac","https:\/\/x.com\/interac","https:\/\/www.instagram.com\/interac\/","https:\/\/www.linkedin.com\/company\/interac-corp\/","https:\/\/www.youtube.com\/user\/InteracBrand"]}]}},"_links":{"self":[{"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/content\/100552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/content"}],"about":[{"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/types\/content"}],"author":[{"embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/users\/28"}],"version-history":[{"count":0,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/content\/100552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/media\/100540"}],"wp:attachment":[{"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/media?parent=100552"}],"wp:term":[{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/content-tags?post=100552"},{"taxonomy":"content-category","embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/content-category?post=100552"},{"taxonomy":"spokespeople","embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/spokespeople?post=100552"},{"taxonomy":"in_the_know_post_format","embeddable":true,"href":"https:\/\/www.interac.ca\/fr\/wp-json\/wp\/v2\/in_the_know_post_format?post=100552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}